
{"id":20971,"date":"2021-10-12T11:00:21","date_gmt":"2021-10-12T04:00:21","guid":{"rendered":"https:\/\/www.media.kmutt.ac.th\/?p=20971"},"modified":"2023-12-17T19:56:47","modified_gmt":"2023-12-17T12:56:47","slug":"%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad","status":"publish","type":"post","link":"https:\/\/media.kmutt.ac.th\/en\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/","title":{"rendered":"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-22070 lazyload\" data-src=\"http:\/\/cmkmutt.wpenginepowered.com\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png\" alt=\"\" width=\"1024\" height=\"768\" data-srcset=\"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png 1024w, https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768-300x225.png 300w, https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768-768x576.png 768w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><noscript><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-22070\" src=\"http:\/\/cmkmutt.wpenginepowered.com\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png 1024w, https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768-300x225.png 300w, https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768-768x576.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/p>\n<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564<\/p>\n<p><strong>\u0e27\u0e31\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 \u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 5 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2564<\/strong><\/p>\n<ol>\n<li>\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a <a href=\"https:\/\/sinfo.kmutt.ac.th\/\">https:\/\/sinfo.kmutt.ac.th\/\u2028<\/a><\/li>\n<li>\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e21\u0e19\u0e39 &#8220;\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a&#8221;\u2028<\/li>\n<li>\u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19&#8221;\u2028<\/li>\n<li>\u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32&#8221;\u2028<\/li>\n<li>\u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32&#8221; \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e14\u0e2a\u0e48\u0e07 &#8220;\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07&#8221;<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564 \u0e27\u0e31\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 \u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 5 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2564 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a https:\/\/sinfo.kmutt.ac.th\/\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e21\u0e19\u0e39 &#8220;\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a&#8221;\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19&#8221;\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32&#8221;\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32&#8221; \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e14\u0e2a\u0e48\u0e07 &#8220;\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07&#8221;<\/p>","protected":false},"author":1,"featured_media":22070,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,40],"tags":[],"class_list":["post-20971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-student-services","category-current-student"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564 - Creative Media KMUTT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/media.kmutt.ac.th\/en\/\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564 - Creative Media KMUTT\" \/>\n<meta property=\"og:description\" content=\"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564 \u0e27\u0e31\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 \u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 5 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2564 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a https:\/\/sinfo.kmutt.ac.th\/\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e21\u0e19\u0e39 &#8220;\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a&#8221;\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19&#8221;\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32&#8221;\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32&#8221; \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e14\u0e2a\u0e48\u0e07 &#8220;\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07&#8221;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/media.kmutt.ac.th\/en\/\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\/\" \/>\n<meta property=\"og:site_name\" content=\"Creative Media KMUTT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/kmutt.media\/?locale=th_TH\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-12T04:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-17T12:56:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"cm@kmutt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"cm@kmutt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/\"},\"author\":{\"name\":\"cm@kmutt\",\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/#\\\/schema\\\/person\\\/cd175468255d38d18f14747863e3b119\"},\"headline\":\"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\\\/2564\",\"datePublished\":\"2021-10-12T04:00:21+00:00\",\"dateModified\":\"2023-12-17T12:56:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.kmutt.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/244710762_2390456587750895_3598014465352772828_n-1024x768.png\",\"articleSection\":[\"\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\",\"\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/\",\"url\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/\",\"name\":\"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\\\/2564 - Creative Media KMUTT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/media.kmutt.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/244710762_2390456587750895_3598014465352772828_n-1024x768.png\",\"datePublished\":\"2021-10-12T04:00:21+00:00\",\"dateModified\":\"2023-12-17T12:56:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/media.kmutt.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/244710762_2390456587750895_3598014465352772828_n-1024x768.png\",\"contentUrl\":\"https:\\\/\\\/media.kmutt.ac.th\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/244710762_2390456587750895_3598014465352772828_n-1024x768.png\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/media.kmutt.ac.th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\\\/2564\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/#website\",\"url\":\"https:\\\/\\\/media.kmutt.ac.th\\\/\",\"name\":\"Creative Media KMUTT\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/media.kmutt.ac.th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/#organization\",\"name\":\"Creative Media KMUTT\",\"url\":\"https:\\\/\\\/media.kmutt.ac.th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/media.kmutt.ac.th\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/media.kmutt.ac.th\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/logo.png\",\"width\":581,\"height\":416,\"caption\":\"Creative Media KMUTT\"},\"image\":{\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kmutt.media\\\/?locale=th_TH\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/media.kmutt.ac.th\\\/#\\\/schema\\\/person\\\/cd175468255d38d18f14747863e3b119\",\"name\":\"cm@kmutt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75fc3d6574edc67b841fbd5d0ab8a4b765ec9bbf1cb98718a20ec3569c694331?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75fc3d6574edc67b841fbd5d0ab8a4b765ec9bbf1cb98718a20ec3569c694331?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/75fc3d6574edc67b841fbd5d0ab8a4b765ec9bbf1cb98718a20ec3569c694331?s=96&d=mm&r=g\",\"caption\":\"cm@kmutt\"},\"sameAs\":[\"http:\\\/\\\/cmkmutt.wpenginepowered.com\"],\"url\":\"https:\\\/\\\/media.kmutt.ac.th\\\/en\\\/author\\\/cmkmutt\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564 - Creative Media KMUTT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/media.kmutt.ac.th\/en\/\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\/","og_locale":"en_US","og_type":"article","og_title":"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564 - Creative Media KMUTT","og_description":"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564 \u0e27\u0e31\u0e19\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 \u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 5 \u0e1e\u0e24\u0e28\u0e08\u0e34\u0e01\u0e32\u0e22\u0e19 2564 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e30\u0e1a\u0e1a https:\/\/sinfo.kmutt.ac.th\/\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e21\u0e19\u0e39 &#8220;\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e27\u0e47\u0e1a&#8221;\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19&#8221;\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e22\u0e37\u0e48\u0e19\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32&#8221;\u2028 \u0e40\u0e25\u0e37\u0e2d\u0e01 &#8220;\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32&#8221; \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e14\u0e2a\u0e48\u0e07 &#8220;\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07&#8221;","og_url":"https:\/\/media.kmutt.ac.th\/en\/\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\/","og_site_name":"Creative Media KMUTT","article_publisher":"https:\/\/www.facebook.com\/kmutt.media\/?locale=th_TH","article_published_time":"2021-10-12T04:00:21+00:00","article_modified_time":"2023-12-17T12:56:47+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png","type":"image\/png"}],"author":"cm@kmutt","twitter_card":"summary_large_image","twitter_misc":{"Written by":"cm@kmutt","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/#article","isPartOf":{"@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/"},"author":{"name":"cm@kmutt","@id":"https:\/\/media.kmutt.ac.th\/#\/schema\/person\/cd175468255d38d18f14747863e3b119"},"headline":"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564","datePublished":"2021-10-12T04:00:21+00:00","dateModified":"2023-12-17T12:56:47+00:00","mainEntityOfPage":{"@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/"},"wordCount":5,"publisher":{"@id":"https:\/\/media.kmutt.ac.th\/#organization"},"image":{"@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/#primaryimage"},"thumbnailUrl":"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png","articleSection":["\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32","\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/","url":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/","name":"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564 - Creative Media KMUTT","isPartOf":{"@id":"https:\/\/media.kmutt.ac.th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/#primaryimage"},"image":{"@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/#primaryimage"},"thumbnailUrl":"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png","datePublished":"2021-10-12T04:00:21+00:00","dateModified":"2023-12-17T12:56:47+00:00","breadcrumb":{"@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/#primaryimage","url":"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png","contentUrl":"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2023\/11\/244710762_2390456587750895_3598014465352772828_n-1024x768.png","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/media.kmutt.ac.th\/%e0%b8%82%e0%b8%b1%e0%b9%89%e0%b8%99%e0%b8%95%e0%b8%ad%e0%b8%99%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%96%e0%b8%ad%e0%b8%99%e0%b8%a3%e0%b8%b2%e0%b8%a2%e0%b8%a7%e0%b8%b4%e0%b8%8a%e0%b8%b2%e0%b8%ad%e0%b8%ad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/media.kmutt.ac.th\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e31\u0e49\u0e19\u0e15\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e16\u0e2d\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e33\u0e23\u0e49\u0e2d\u0e07 1\/2564"}]},{"@type":"WebSite","@id":"https:\/\/media.kmutt.ac.th\/#website","url":"https:\/\/media.kmutt.ac.th\/","name":"Creative Media KMUTT","description":"","publisher":{"@id":"https:\/\/media.kmutt.ac.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/media.kmutt.ac.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/media.kmutt.ac.th\/#organization","name":"Creative Media KMUTT","url":"https:\/\/media.kmutt.ac.th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/media.kmutt.ac.th\/#\/schema\/logo\/image\/","url":"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2024\/05\/logo.png","contentUrl":"https:\/\/media.kmutt.ac.th\/wp-content\/uploads\/2024\/05\/logo.png","width":581,"height":416,"caption":"Creative Media KMUTT"},"image":{"@id":"https:\/\/media.kmutt.ac.th\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kmutt.media\/?locale=th_TH"]},{"@type":"Person","@id":"https:\/\/media.kmutt.ac.th\/#\/schema\/person\/cd175468255d38d18f14747863e3b119","name":"cm@kmutt","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/75fc3d6574edc67b841fbd5d0ab8a4b765ec9bbf1cb98718a20ec3569c694331?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/75fc3d6574edc67b841fbd5d0ab8a4b765ec9bbf1cb98718a20ec3569c694331?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/75fc3d6574edc67b841fbd5d0ab8a4b765ec9bbf1cb98718a20ec3569c694331?s=96&d=mm&r=g","caption":"cm@kmutt"},"sameAs":["http:\/\/cmkmutt.wpenginepowered.com"],"url":"https:\/\/media.kmutt.ac.th\/en\/author\/cmkmutt\/"}]}},"_links":{"self":[{"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/posts\/20971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/comments?post=20971"}],"version-history":[{"count":0,"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/posts\/20971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/media\/22070"}],"wp:attachment":[{"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/media?parent=20971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/categories?post=20971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/media.kmutt.ac.th\/en\/wp-json\/wp\/v2\/tags?post=20971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}